{"id":58432,"date":"2025-12-18T09:00:00","date_gmt":"2025-12-18T08:00:00","guid":{"rendered":"https:\/\/www.crowdfarming.com\/what-the-field\/non-categorise\/recette-de-la-tarte-aux-pommes-et-aux-noix\/"},"modified":"2026-05-04T12:34:57","modified_gmt":"2026-05-04T10:34:57","slug":"recette-de-la-tarte-aux-pommes-et-aux-noix","status":"publish","type":"post","link":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/","title":{"rendered":"Recette de la tarte aux pommes et aux noix"},"content":{"rendered":"&#13;\n<p>\u00c0 l&rsquo;approche des f\u00eates de fin d&rsquo;ann\u00e9e, notre agricultrice Kathrin Wiest, de <a href=\"https:\/\/www.crowdfarming.com\/en\/farmer\/biohof-hund\/up\/buy-early-apples-biohof-hund\/overharvest?utm_source=https%3A%2F%2Fwww.crowdfarming.com%2Fblog%2Fen%2F&amp;utm_medium=Referral&amp;utm_campaign=AppleRecipe_CF_BP&amp;utm_term=Blog+CF\" target=\"_blank\" rel=\"noreferrer noopener\">Biohof Hund<\/a>, a partag\u00e9 l&rsquo;une de ses recettes saisonni\u00e8res pr\u00e9f\u00e9r\u00e9es : une tarte aux pommes et aux noix, transmise de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration dans sa famille.<br\/><br\/>Kathrin a grandi en passant ses week-ends dans la ferme de ses grands-parents, o\u00f9 elle aidait \u00e0 la r\u00e9colte du foin, \u00e0 la traite des vaches, \u00e0 la r\u00e9colte des l\u00e9gumes, et o\u00f9 elle a d\u00e9couvert tr\u00e8s t\u00f4t l&rsquo;importance de savoir d&rsquo;o\u00f9 vient ce que l&rsquo;on mange. \u00ab\u00a0La bonne nourriture ne commence pas dans la cuisine, dit-elle, elle commence dans le champ. <br\/><br\/>Cette profonde appr\u00e9ciation de la terre l&rsquo;a suivie tout au long de sa carri\u00e8re dans la gastronomie et maintenant dans son travail \u00e0 Biohof Hund, o\u00f9 elle combine ses diverses exp\u00e9riences dans la gastronomie, l&rsquo;agriculture biologique et l&rsquo;horticulture.<br\/><br\/>Pour Kathryn, travailler \u00e0 la ferme est plus qu&rsquo;un simple travail : \u00ab\u00a0C&rsquo;est un retour aux sources, dit-elle, un choix conscient de durabilit\u00e9 et de r\u00e9gionalit\u00e9, et un pas vers un avenir qui a vraiment du sens &#8211; pour ma famille, pour notre ferme et pour la soci\u00e9t\u00e9 dans son ensemble.<br\/><br\/>Pour Kathrin, cette recette refl\u00e8te les valeurs avec lesquelles elle a grandi : simplicit\u00e9, saisonnalit\u00e9 et lien significatif avec la terre.<br\/><br\/>Dans cette recette simple et d\u00e9licieuse, les pommes sont dispos\u00e9es sur une riche cr\u00e8me de noix et une cro\u00fbte moelleuse au beurre : le dessert parfait pour cet hiver.<br\/><br\/>Conservez cette recette pour vos prochaines f\u00eates de fin d&rsquo;ann\u00e9e !<br\/><br\/><\/p>&#13;\n&#13;\n<h2 class=\"wp-block-heading\">Tarte aux pommes et aux noix<br\/><br\/><\/h2>&#13;\n&#13;\n<p>Ingr\u00e9dients :<\/p>&#13;\n&#13;\n<ul class=\"wp-block-list\">&#13;\n<li>  300 g de farine d&rsquo;\u00e9peautre (plus un peu pour saupoudrer)<\/li>&#13;\n<li>120 g de sucre roux<\/li>&#13;\n<li>Pinc\u00e9e de sel<\/li>&#13;\n<li>2 \u0153ufs moyens<\/li>&#13;\n<li>200 g de beurre (130 g froid, 70 g ramolli, plus un peu pour le graissage)<\/li>&#13;\n<li>1 kg de pommes acidul\u00e9es<\/li>&#13;\n<li>2 cuill\u00e8res \u00e0 soupe de jus de citron<\/li>&#13;\n<li>150 g de moiti\u00e9s de noix<\/li>&#13;\n<li>1 sachet de sucre vanill\u00e9<\/li>&#13;\n<li>50 g de miel<\/li>&#13;\n<li>80 ml de cr\u00e8me double<\/li>&#13;\n<li>1 pinc\u00e9e de cannelle moulue<br\/><br\/><\/li>&#13;\n<\/ul>&#13;\n&#13;\n<p>Pr\u00e9paration :<\/p>&#13;\n&#13;\n<p>Placez 250 g de farine, 70 g de sucre, une pinc\u00e9e de sel, 1 \u0153uf et 130 g de beurre froid (coup\u00e9 en morceaux) dans un saladier. M\u00e9langez d&rsquo;abord avec les crochets d&rsquo;un batteur \u00e0 main, puis p\u00e9trissez bri\u00e8vement \u00e0 la main jusqu&rsquo;\u00e0 l&rsquo;obtention d&rsquo;une p\u00e2te lisse. Formez un disque, enveloppez-le dans du film alimentaire et mettez-le au r\u00e9frig\u00e9rateur pendant 30 minutes.  <br\/><br\/>\u00c9pluchez les pommes, coupez-les en quatre, enlevez le c\u0153ur et coupez-les en fines tranches. M\u00e9langez-les avec le jus de citron. <br\/><br\/>Pour la garniture, broyez finement 50 g de noix dans un robot. Battez 50 g de beurre mou, 50 g de sucre, le sucre vanill\u00e9 et une pinc\u00e9e de sel \u00e0 l&rsquo;aide d&rsquo;un batteur \u00e0 main jusqu&rsquo;\u00e0 l&rsquo;obtention d&rsquo;une consistance tr\u00e8s cr\u00e9meuse. Incorporez 1 \u0153uf. Ajoutez les noix moulues et 50 g de farine et m\u00e9langez bri\u00e8vement.   <br\/><br\/>Pr\u00e9chauffez le four \u00e0 200\u00b0C (180\u00b0C en mode ventilation). \u00c9talez la p\u00e2te refroidie sur une surface farin\u00e9e jusqu&rsquo;\u00e0 ce qu&rsquo;elle atteigne environ 30 cm de diam\u00e8tre et tapissez-en un moule \u00e0 tarte ou \u00e0 charni\u00e8re de 28 cm graiss\u00e9. Pressez la p\u00e2te sur les c\u00f4t\u00e9s et piquez le fond plusieurs fois \u00e0 l&rsquo;aide d&rsquo;une fourchette.  <br\/><br\/>\u00c9talez la cr\u00e8me de noix sur la base et disposez les tranches de pommes sur le dessus. Faites cuire sur une grille pos\u00e9e directement sur la sole du four pendant 25 minutes. <br\/><br\/>Pendant ce temps, pour la garniture aux noix, hachez grossi\u00e8rement les 100 g de noix restants. Dans une petite casserole, faites chauffer le miel, la cr\u00e8me, la cannelle et 20 g de beurre, portez \u00e0 \u00e9bullition en remuant et laissez mijoter pendant 2 minutes. Incorporez les noix.  <br\/><br\/>Apr\u00e8s 25 minutes de cuisson de la tarte, versez le m\u00e9lange de noix sur les pommes et poursuivez la cuisson pendant 10 minutes sur la grille du milieu.<br\/><br\/>Laissez refroidir dans le moule sur une grille. D\u00e9moulez d\u00e9licatement et servez avec de la cr\u00e8me fouett\u00e9e. <\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>&#13; \u00c0 l&rsquo;approche des f\u00eates de fin d&rsquo;ann\u00e9e, notre agricultrice Kathrin Wiest, de Biohof Hund, a partag\u00e9 l&rsquo;une de ses recettes saisonni\u00e8res pr\u00e9f\u00e9r\u00e9es : une tarte aux pommes et aux noix, transmise de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration dans sa famille. Kathrin a grandi en passant ses week-ends dans la ferme de ses grands-parents, o\u00f9 elle aidait [&hellip;]<\/p>\n","protected":false},"author":176,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[489],"tags":[6076,6077,6078,5711,5713,1454],"class_list":["post-58432","post","type-post","status-publish","format-standard","hentry","category-recettes-de-cuisine","tag-recette-de-cuisson","tag-tarte-aux-noix","tag-patisserie-dhiver","tag-dessert-de-saison","tag-tarte-aux-pommes","tag-agriculture-biologique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin<\/title>\n<meta name=\"description\" content=\"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin : un dessert familial de saison avec des pommes, des noix et une cro\u00fbte beurr\u00e9e pour les rassemblements hivernaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin\" \/>\n<meta property=\"og:description\" content=\"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin : un dessert familial de saison avec des pommes, des noix et une cro\u00fbte beurr\u00e9e pour les rassemblements hivernaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/\" \/>\n<meta property=\"og:site_name\" content=\"WTF\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T10:34:57+00:00\" \/>\n<meta name=\"author\" content=\"Sofia Cadahia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sofia Cadahia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/\"},\"author\":{\"name\":\"Sofia Cadahia\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/3d35aad44a815ac393f39ad1ad55ee93\"},\"headline\":\"Recette de la tarte aux pommes et aux noix\",\"datePublished\":\"2025-12-18T08:00:00+00:00\",\"dateModified\":\"2026-05-04T10:34:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/\"},\"wordCount\":700,\"keywords\":[\"recette de cuisson\",\"tarte aux noix\",\"p\u00e2tisserie d'hiver\",\"dessert de saison\",\"tarte aux pommes\",\"agriculture biologique\"],\"articleSection\":[\"Recettes\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/\",\"url\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/\",\"name\":\"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\"},\"datePublished\":\"2025-12-18T08:00:00+00:00\",\"dateModified\":\"2026-05-04T10:34:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/3d35aad44a815ac393f39ad1ad55ee93\"},\"description\":\"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin : un dessert familial de saison avec des pommes, des noix et une cro\u00fbte beurr\u00e9e pour les rassemblements hivernaux.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/recettes-de-cuisine\\\/recette-de-la-tarte-aux-pommes-et-aux-noix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recette de la tarte aux pommes et aux noix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#website\",\"url\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/\",\"name\":\"WTF\",\"description\":\"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laruchequiditoui.fr\\\/fr\\\/what-the-field\\\/#\\\/schema\\\/person\\\/3d35aad44a815ac393f39ad1ad55ee93\",\"name\":\"Sofia Cadahia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sofia-cadahia-150x150.jpg\",\"url\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sofia-cadahia-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/sofia-cadahia-150x150.jpg\",\"caption\":\"Sofia Cadahia\"},\"description\":\"Sofia is What The Field!?\u2019s Nutrition &amp; Food Science Editor, working at the intersection of nutrition, sustainability, and environmental justice. As a Registered Dietitian Nutritionist with a background in Digital Marketing, she uses storytelling to explore how food systems shape health, equity, and environmental outcomes, as well as the often unseen forces that determine what ends up on our plates.\",\"url\":\"https:\\\/\\\/www.crowdfarming.com\\\/what-the-field\\\/fr\\\/author\\\/sofia-cadahia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin","description":"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin : un dessert familial de saison avec des pommes, des noix et une cro\u00fbte beurr\u00e9e pour les rassemblements hivernaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/","og_locale":"fr_FR","og_type":"article","og_title":"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin","og_description":"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin : un dessert familial de saison avec des pommes, des noix et une cro\u00fbte beurr\u00e9e pour les rassemblements hivernaux.","og_url":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/","og_site_name":"WTF","article_published_time":"2025-12-18T08:00:00+00:00","article_modified_time":"2026-05-04T10:34:57+00:00","author":"Sofia Cadahia","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sofia Cadahia","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/#article","isPartOf":{"@id":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/"},"author":{"name":"Sofia Cadahia","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/3d35aad44a815ac393f39ad1ad55ee93"},"headline":"Recette de la tarte aux pommes et aux noix","datePublished":"2025-12-18T08:00:00+00:00","dateModified":"2026-05-04T10:34:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/"},"wordCount":700,"keywords":["recette de cuisson","tarte aux noix","p\u00e2tisserie d'hiver","dessert de saison","tarte aux pommes","agriculture biologique"],"articleSection":["Recettes"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/","url":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/","name":"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin","isPartOf":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website"},"datePublished":"2025-12-18T08:00:00+00:00","dateModified":"2026-05-04T10:34:57+00:00","author":{"@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/3d35aad44a815ac393f39ad1ad55ee93"},"description":"Recette de la tarte aux pommes et aux noix de la fermi\u00e8re Kathrin : un dessert familial de saison avec des pommes, des noix et une cro\u00fbte beurr\u00e9e pour les rassemblements hivernaux.","breadcrumb":{"@id":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/recettes-de-cuisine\/recette-de-la-tarte-aux-pommes-et-aux-noix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/"},{"@type":"ListItem","position":2,"name":"Recette de la tarte aux pommes et aux noix"}]},{"@type":"WebSite","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#website","url":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/","name":"WTF","description":"Una plataforma de informaci\u00f3n sobre nuestro sistema agro-alimentario.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/laruchequiditoui.fr\/fr\/what-the-field\/#\/schema\/person\/3d35aad44a815ac393f39ad1ad55ee93","name":"Sofia Cadahia","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2026\/01\/sofia-cadahia-150x150.jpg","url":"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2026\/01\/sofia-cadahia-150x150.jpg","contentUrl":"https:\/\/www.crowdfarming.com\/what-the-field\/wp-content\/uploads\/2026\/01\/sofia-cadahia-150x150.jpg","caption":"Sofia Cadahia"},"description":"Sofia is What The Field!?\u2019s Nutrition &amp; Food Science Editor, working at the intersection of nutrition, sustainability, and environmental justice. As a Registered Dietitian Nutritionist with a background in Digital Marketing, she uses storytelling to explore how food systems shape health, equity, and environmental outcomes, as well as the often unseen forces that determine what ends up on our plates.","url":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/author\/sofia-cadahia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/posts\/58432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/users\/176"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/comments?post=58432"}],"version-history":[{"count":1,"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/posts\/58432\/revisions"}],"predecessor-version":[{"id":58433,"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/posts\/58432\/revisions\/58433"}],"wp:attachment":[{"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/media?parent=58432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/categories?post=58432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crowdfarming.com\/what-the-field\/fr\/wp-json\/wp\/v2\/tags?post=58432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}